{"id":35965,"date":"2024-10-04T00:06:41","date_gmt":"2024-10-04T00:06:41","guid":{"rendered":"https:\/\/store.handsomecake.com\/produkt\/naruto-orochimaru-17-resin-statue-von-vortex-studio\/"},"modified":"2024-10-04T02:01:56","modified_gmt":"2024-10-04T02:01:56","slug":"naruto-orochimaru-17-resin-statue-von-vortex-studio","status":"publish","type":"product","link":"https:\/\/store.handsomecake.com\/en\/product\/naruto-orochimaru-17-resin-statue-von-vortex-studio\/","title":{"rendered":"Naruto &#8211; Orochimaru | 1:7 Resin Statue | von Vortex Studio"},"content":{"rendered":"<p><strong>Naruto &#8211; Orochimaru | 1:7 Resin Statue | von Vortex Studio<\/strong><\/p>\n<p>EU Taxfree! I do ship EU-wide, please contact me, should questions arise.<\/p>\n<p>Tolle Statue von einem Nukenin aus Konohagakure.<br \/>\nWunderbar verarbeitete und sehr detaillierte Statue von Orochimaru aus Polystone &#8211; k\u00fcnstlichem Stein-Harz-Gemisch.<\/p>\n<p><strong>Besonderheiten:<\/strong><\/p>\n<ul>\n<li>weltweit auf 188 St\u00fcck begrenzt<\/li>\n<\/ul>\n<p><strong>Release-Status:<\/strong><\/p>\n<ul>\n<li>Preorder. Voraussichtlicher Release-Termin: Q4 2025, voraussichtlich bei uns im Lager: Ende Februar 2026.<\/li>\n<li>Diese Angabe ist ohne Gew\u00e4hr! Wir leiten nur die Sch\u00e4tzung vom Hersteller weiter.<\/li>\n<li>Falls das Datum \u00fcberschritten wurde und hier immer noch eine Sch\u00e4tzung aus der Vergangenheit steht, dann bedeutet das NICHT, dass die Figur bereits im Lager in Deutschland ist. Sie ist NUR dann auf Lager in Deutschland, wenn der Text dies entsprechend sagt und\/oder die Kategorie weiter oben &#8222;Lagernd vor Ort&#8220; hei\u00dft.<\/li>\n<\/ul>\n<hr \/>\n<p>Wie immer bei unseren Artikeln &#8211; s\u00e4mtliche Geb\u00fchren sind, im Gegensatz zu anderen Anbietern auf dem Markt, bereits inkludiert.<\/p>\n<p>Versand erfolgt ausschlie\u00dflich aus Deutschland, es fallen keine Zoll- und Importgeb\u00fchren an.<\/p>\n<p>Als einziger EU-weit legal zugelassener H\u00e4ndler von Resin-Statuen garantieren wir exklusive Qualit\u00e4t und Vertrauensw\u00fcrdigkeit, die ihr nirgendwo anders finden.<\/p>\n<p>Ihr kauft keine Katze im Sack \ud83d\ude42<\/p>\n<hr \/>\n<p>You are not prepared! \ud83d\ude42<\/p>","protected":false},"excerpt":{"rendered":"<p>Naruto &#8211; Orochimaru | 1:7 Resin Statue | von Vortex Studio EU Taxfree! I do ship EU-wide, please contact me, should questions arise. Tolle Statue von einem Nukenin aus Konohagakure. Wunderbar verarbeitete und sehr detaillierte Statue von Orochimaru aus Polystone &#8211; k\u00fcnstlichem Stein-Harz-Gemisch. Besonderheiten: weltweit auf 188 St\u00fcck begrenzt Release-Status: Preorder. Voraussichtlicher Release-Termin: Q4 2025, [&hellip;]<\/p>\n","protected":false},"featured_media":36043,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[24,88,568,84],"product_tag":[656,659,660,657,640,658,147,251,168,296,3620,3622,169,170,3621,3623,154,136,137],"class_list":{"0":"post-35965","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-action-figuren","7":"product_cat-naruto","8":"product_cat-preorder","9":"product_cat-statuen-anime-comic-universum","10":"product_tag-anime-collectibles","11":"product_tag-anime-figuren","12":"product_tag-anime-figuren-naruto","13":"product_tag-anime-figures","14":"product_tag-anime-statuen","15":"product_tag-anime-toys","16":"product_tag-collectibles","17":"product_tag-collectibles-kaufen","18":"product_tag-naruto-collectibles","19":"product_tag-naruto-collectibles-kaufen","20":"product_tag-naruto-orochimaru","21":"product_tag-naruto-orochimaru-statue","22":"product_tag-naruto-statuen","23":"product_tag-naruto-statuen-kaufen","24":"product_tag-orochimaru","25":"product_tag-orochimaru-collectible","26":"product_tag-resin-collectibles","27":"product_tag-resin-statuen","28":"product_tag-resin-statuen-kaufen","29":"pa_brand-vortex-studio","30":"pa_scale-1_to_7","32":"first","33":"instock","34":"taxable","35":"shipping-taxable","36":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/store.handsomecake.com\/en\/wp-json\/wp\/v2\/product\/35965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/store.handsomecake.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/store.handsomecake.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/store.handsomecake.com\/en\/wp-json\/wp\/v2\/comments?post=35965"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/store.handsomecake.com\/en\/wp-json\/wp\/v2\/media\/36043"}],"wp:attachment":[{"href":"https:\/\/store.handsomecake.com\/en\/wp-json\/wp\/v2\/media?parent=35965"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/store.handsomecake.com\/en\/wp-json\/wp\/v2\/product_brand?post=35965"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/store.handsomecake.com\/en\/wp-json\/wp\/v2\/product_cat?post=35965"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/store.handsomecake.com\/en\/wp-json\/wp\/v2\/product_tag?post=35965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}