{"id":4162,"date":"2021-08-02T20:44:13","date_gmt":"2021-08-02T20:44:13","guid":{"rendered":"https:\/\/store.handsomecake.com\/?page_id=4162"},"modified":"2022-08-23T07:01:42","modified_gmt":"2022-08-23T07:01:42","slug":"schreibt-uns","status":"publish","type":"page","link":"https:\/\/store.handsomecake.com\/en\/schreibt-uns\/","title":{"rendered":"Schreibt uns!"},"content":{"rendered":"\n<p>Habt ihr eine allgemeine Frage oder eine Anregung? Schreibt uns eine kurze Nachricht und wir melden uns:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>innerhalb von 72 Stunden bei allgemeinen Anfragen<\/li><li>innerhalb von 5 Werktagen bei Fragen zum Status einer Bestellung (siehe unten)<\/li><li>innerhalb von 14 Werktagen bei Stornierungsanfragen<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Diese kleine Liste hilft uns allen, viel Arbeit zu ersparen und euch schnell mit Antworten zu versorgen:<\/h4>\n\n\n\n<ol class=\"wp-block-list\"><li><strong><span style=\"text-decoration: underline;\">Bei allen Fragen zum Thema:<\/span><\/strong><ul><li><strong>Wo ist meine Bestellung?<\/strong><\/li><li><strong>Wie ist der Status meiner Bestellung?<\/strong><\/li><li><strong>Gibt es Neuigkeiten zu meiner Bestellung?<\/strong><\/li><li>&#8212;-&gt; <a href=\"https:\/\/store.handsomecake.com\/vor-einer-bestellung-bitte-unbedingt-durchlesen\/\" data-type=\"URL\" data-id=\"https:\/\/store.handsomecake.com\/vor-einer-bestellung-bitte-unbedingt-durchlesen\/\">bitte ich zuerst diesen Post durchzulesen<\/a>.<\/li><\/ul><\/li><li>Ist die Statue XY lieferbar\/lagernd? &#8211; Wir haben einen tollen <a href=\"https:\/\/store.handsomecake.com\/faq\/\" data-type=\"URL\" data-id=\"https:\/\/store.handsomecake.com\/faq\/\">FAQ-Beitrag<\/a> dazu.<\/li><\/ol>\n\n\n\n<p>Falls die Frage weiterhin ungekl\u00e4rt ist, hinterlasst eine kurze Nachricht:<\/p>\n\n\n<p>[zendesk_request_form label_name=&#8220;Dein Vorname&#8220; ]<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Habt ihr eine allgemeine Frage oder eine Anregung? Schreibt uns eine kurze Nachricht und wir melden uns: innerhalb von 72 Stunden bei allgemeinen Anfragen innerhalb von 5 Werktagen bei Fragen zum Status einer Bestellung (siehe unten) innerhalb von 14 Werktagen bei Stornierungsanfragen Diese kleine Liste hilft uns allen, viel Arbeit zu ersparen und euch schnell [&hellip;]<\/p>\n","protected":false},"author":985,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4162","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/store.handsomecake.com\/en\/wp-json\/wp\/v2\/pages\/4162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/store.handsomecake.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/store.handsomecake.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/store.handsomecake.com\/en\/wp-json\/wp\/v2\/users\/985"}],"replies":[{"embeddable":true,"href":"https:\/\/store.handsomecake.com\/en\/wp-json\/wp\/v2\/comments?post=4162"}],"version-history":[{"count":0,"href":"https:\/\/store.handsomecake.com\/en\/wp-json\/wp\/v2\/pages\/4162\/revisions"}],"wp:attachment":[{"href":"https:\/\/store.handsomecake.com\/en\/wp-json\/wp\/v2\/media?parent=4162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}